﻿{"id":2035,"date":"2015-09-18T13:48:53","date_gmt":"2015-09-18T13:48:53","guid":{"rendered":"http:\/\/walex.eu\/product\/desodorante-deenzimas-naturales-bio-pak\/"},"modified":"2015-11-24T09:02:21","modified_gmt":"2015-11-24T09:02:21","slug":"desodorante-deenzimas-naturales-bio-pak","status":"publish","type":"product","link":"https:\/\/walex.eu\/es\/shop\/desodorante-deenzimas-naturales-bio-pak\/","title":{"rendered":"Desodorante y digeridor biol\u00f3gico Bio-Pak"},"content":{"rendered":"<p><strong><em>Desodorante y digeridor\u00a0biol\u00f3gico de\u00a0desechos<\/em><\/strong><\/p>\n<p>Bio-Pak bolsitas desodorantes biol\u00f3gicas son el resultado de una amplia investigaci\u00f3n de I + D del Grupo Walex en el descubrimiento de nuevas enzimas naturales, <br \/>para eliminar el olor y licuar los residuos.<br \/>Despu\u00e9s de una sola Bio-Pak Express se dej\u00f3 caer en el dep\u00f3sito de desechos\u00a0y se a\u00f1ade agua, la ruptura de papel y otros residuos se iniciar\u00e1 de inmediato,<br \/>junto con la difusi\u00f3n de una aroma fresca.<\/p>\n<p>Walex\u00ae Porta-Pak:<br \/>250 bolsitas desodorantes (Caja con 5 bolsas que contienen 50 Bio-Pak\u00a0bolsitas)<br \/>1 a la proporci\u00f3n de 20 litros<br \/>Fragancia: Sunglow<br \/>Listo para usar<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong><em>Desodorante y digeridor\u00a0biol\u00f3gico de\u00a0desechos<\/em><\/strong><\/p>\n<p>Bio-Pak bolsitas desodorantes biol\u00f3gicas son el resultado de una amplia investigaci\u00f3n de I + D del Grupo Walex en el descubrimiento de nuevas enzimas naturales, <br \/>para eliminar el olor y descomponer\u00a0los desechos.<\/p>\n<p> <a class=\"continue-reading\" href=\"https:\/\/walex.eu\/es\/shop\/desodorante-deenzimas-naturales-bio-pak\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"featured_media":795,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[414],"product_tag":[703,565,1042,978,663,1007,711,913,1158,975,785],"class_list":["post-2035","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-bolsitas-de-polvo","product_tag-amigable-con-el-medio-ambiente","product_tag-bacterias-es-2","product_tag-bolsita","product_tag-control-de-la-cantidad","product_tag-desodorizante","product_tag-empresas-de-alquiler","product_tag-enzimas-es","product_tag-supresion-de-olores","product_tag-tratamiento-de-desechos","product_tag-urinarios-portatiles","product_tag-verde-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Desodorante y digeridor biol\u00f3gico Bio-Pak - Walex<\/title>\n<meta name=\"description\" content=\"Desodorante y digeridor biol\u00f3gico de desechos Bio-Pak elimina el olor y descomponer los desechos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walex.eu\/es\/shop\/desodorante-deenzimas-naturales-bio-pak\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desodorante y digeridor biol\u00f3gico Bio-Pak - Walex\" \/>\n<meta property=\"og:description\" content=\"Desodorante y digeridor biol\u00f3gico de desechos Bio-Pak elimina el olor y descomponer los desechos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walex.eu\/es\/shop\/desodorante-deenzimas-naturales-bio-pak\/\" \/>\n<meta property=\"og:site_name\" content=\"Walex\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-24T09:02:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/walex.eu\/wp-content\/uploads\/2015\/09\/Biological-deodorant-sachets-Bio-Pak.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/walex.eu\/es\/shop\/desodorante-deenzimas-naturales-bio-pak\/\",\"url\":\"https:\/\/walex.eu\/es\/shop\/desodorante-deenzimas-naturales-bio-pak\/\",\"name\":\"Desodorante y digeridor biol\u00f3gico Bio-Pak - Walex\",\"isPartOf\":{\"@id\":\"https:\/\/walex.eu\/#website\"},\"datePublished\":\"2015-09-18T13:48:53+00:00\",\"dateModified\":\"2015-11-24T09:02:21+00:00\",\"description\":\"Desodorante y digeridor biol\u00f3gico de desechos Bio-Pak elimina el olor y descomponer los desechos.\",\"breadcrumb\":{\"@id\":\"https:\/\/walex.eu\/es\/shop\/desodorante-deenzimas-naturales-bio-pak\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/walex.eu\/es\/shop\/desodorante-deenzimas-naturales-bio-pak\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/walex.eu\/es\/shop\/desodorante-deenzimas-naturales-bio-pak\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/walex.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/walex.eu\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Desodorante y digeridor biol\u00f3gico Bio-Pak\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/walex.eu\/#website\",\"url\":\"https:\/\/walex.eu\/\",\"name\":\"Walex\",\"description\":\"Desodorantes para ba\u00f1os port\u00e1tiles\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/walex.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desodorante y digeridor biol\u00f3gico Bio-Pak - Walex","description":"Desodorante y digeridor biol\u00f3gico de desechos Bio-Pak elimina el olor y descomponer los desechos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walex.eu\/es\/shop\/desodorante-deenzimas-naturales-bio-pak\/","og_locale":"es_ES","og_type":"article","og_title":"Desodorante y digeridor biol\u00f3gico Bio-Pak - Walex","og_description":"Desodorante y digeridor biol\u00f3gico de desechos Bio-Pak elimina el olor y descomponer los desechos.","og_url":"https:\/\/walex.eu\/es\/shop\/desodorante-deenzimas-naturales-bio-pak\/","og_site_name":"Walex","article_modified_time":"2015-11-24T09:02:21+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/walex.eu\/wp-content\/uploads\/2015\/09\/Biological-deodorant-sachets-Bio-Pak.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walex.eu\/es\/shop\/desodorante-deenzimas-naturales-bio-pak\/","url":"https:\/\/walex.eu\/es\/shop\/desodorante-deenzimas-naturales-bio-pak\/","name":"Desodorante y digeridor biol\u00f3gico Bio-Pak - Walex","isPartOf":{"@id":"https:\/\/walex.eu\/#website"},"datePublished":"2015-09-18T13:48:53+00:00","dateModified":"2015-11-24T09:02:21+00:00","description":"Desodorante y digeridor biol\u00f3gico de desechos Bio-Pak elimina el olor y descomponer los desechos.","breadcrumb":{"@id":"https:\/\/walex.eu\/es\/shop\/desodorante-deenzimas-naturales-bio-pak\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walex.eu\/es\/shop\/desodorante-deenzimas-naturales-bio-pak\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walex.eu\/es\/shop\/desodorante-deenzimas-naturales-bio-pak\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walex.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/walex.eu\/shop\/"},{"@type":"ListItem","position":3,"name":"Desodorante y digeridor biol\u00f3gico Bio-Pak"}]},{"@type":"WebSite","@id":"https:\/\/walex.eu\/#website","url":"https:\/\/walex.eu\/","name":"Walex","description":"Desodorantes para ba\u00f1os port\u00e1tiles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walex.eu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/walex.eu\/es\/wp-json\/wp\/v2\/product\/2035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walex.eu\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/walex.eu\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/walex.eu\/es\/wp-json\/wp\/v2\/comments?post=2035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walex.eu\/es\/wp-json\/wp\/v2\/media\/795"}],"wp:attachment":[{"href":"https:\/\/walex.eu\/es\/wp-json\/wp\/v2\/media?parent=2035"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/walex.eu\/es\/wp-json\/wp\/v2\/product_cat?post=2035"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/walex.eu\/es\/wp-json\/wp\/v2\/product_tag?post=2035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}